{"id":27623,"date":"2019-04-22T10:45:55","date_gmt":"2019-04-22T10:45:55","guid":{"rendered":"https:\/\/www.galloportugal.com\/receita\/pizza-de-mascarpone-azeitonas-e-pesto\/"},"modified":"2020-05-11T12:15:58","modified_gmt":"2020-05-11T12:15:58","slug":"mascarpone-oliwki-i-pesto-pizza","status":"publish","type":"receita","link":"https:\/\/galloportugal.com\/pl\/receita\/mascarpone-oliwki-i-pesto-pizza\/","title":{"rendered":"Mascarpone, oliwki i pesto pizza"},"content":{"rendered":"","protected":false},"featured_media":56047,"parent":0,"template":"","meta":[],"intolerancia":[],"class_list":["post-27623","receita","type-receita","status-publish","has-post-thumbnail","hentry","receitas_categories-veggie-pl"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/galloportugal.com\/pl\/wp-json\/wp\/v2\/receita\/27623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galloportugal.com\/pl\/wp-json\/wp\/v2\/receita"}],"about":[{"href":"https:\/\/galloportugal.com\/pl\/wp-json\/wp\/v2\/types\/receita"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galloportugal.com\/pl\/wp-json\/wp\/v2\/media\/56047"}],"wp:attachment":[{"href":"https:\/\/galloportugal.com\/pl\/wp-json\/wp\/v2\/media?parent=27623"}],"wp:term":[{"taxonomy":"intolerancia","embeddable":true,"href":"https:\/\/galloportugal.com\/pl\/wp-json\/wp\/v2\/intolerancia?post=27623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}