{"id":15093,"date":"2018-12-05T13:01:55","date_gmt":"2018-12-05T13:01:55","guid":{"rendered":"http:\/\/www.galloportugal.com\/receita\/salada-de-alfaces-com-fatias-de-queijo-de-cabra-amendoas-e-mel\/"},"modified":"2019-12-11T12:47:19","modified_gmt":"2019-12-11T12:47:19","slug":"salada-de-alfaces-com-queijo-de-cabra-amendoas-e-mel","status":"publish","type":"receita","link":"https:\/\/galloportugal.com\/palop\/receita\/salada-de-alfaces-com-queijo-de-cabra-amendoas-e-mel\/","title":{"rendered":"Salada de alfaces com queijo de cabra, am\u00eandoas e mel"},"content":{"rendered":"","protected":false},"featured_media":15094,"parent":0,"template":"","meta":[],"intolerancia":[],"class_list":["post-15093","receita","type-receita","status-publish","has-post-thumbnail","hentry","receitas_categories-saladas-palop"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/galloportugal.com\/palop\/wp-json\/wp\/v2\/receita\/15093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galloportugal.com\/palop\/wp-json\/wp\/v2\/receita"}],"about":[{"href":"https:\/\/galloportugal.com\/palop\/wp-json\/wp\/v2\/types\/receita"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galloportugal.com\/palop\/wp-json\/wp\/v2\/media\/15094"}],"wp:attachment":[{"href":"https:\/\/galloportugal.com\/palop\/wp-json\/wp\/v2\/media?parent=15093"}],"wp:term":[{"taxonomy":"intolerancia","embeddable":true,"href":"https:\/\/galloportugal.com\/palop\/wp-json\/wp\/v2\/intolerancia?post=15093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}