{"id":14843,"date":"2018-12-05T18:31:18","date_gmt":"2018-12-05T18:31:18","guid":{"rendered":"http:\/\/www.galloportugal.com\/receita\/polvo-cozido-a-vapor-servido-com-azeite-dalho-e-pimento-padron-com-vinagre-balsamico-branco-gallo\/"},"modified":"2019-12-12T15:34:58","modified_gmt":"2019-12-12T15:34:58","slug":"pulpo-cocido-al-vapor-con-aceite-de-ajo-y-pimientos-de-padron","status":"publish","type":"receita","link":"https:\/\/galloportugal.com\/es\/receita\/pulpo-cocido-al-vapor-con-aceite-de-ajo-y-pimientos-de-padron\/","title":{"rendered":"Pulpo cocido al vapor, con aceite de ajo y pimientos de Padr\u00f3n"},"content":{"rendered":"","protected":false},"featured_media":2901,"parent":0,"template":"","meta":[],"intolerancia":[],"class_list":["post-14843","receita","type-receita","status-publish","has-post-thumbnail","hentry","receitas_categories-pescados"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/galloportugal.com\/es\/wp-json\/wp\/v2\/receita\/14843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galloportugal.com\/es\/wp-json\/wp\/v2\/receita"}],"about":[{"href":"https:\/\/galloportugal.com\/es\/wp-json\/wp\/v2\/types\/receita"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galloportugal.com\/es\/wp-json\/wp\/v2\/media\/2901"}],"wp:attachment":[{"href":"https:\/\/galloportugal.com\/es\/wp-json\/wp\/v2\/media?parent=14843"}],"wp:term":[{"taxonomy":"intolerancia","embeddable":true,"href":"https:\/\/galloportugal.com\/es\/wp-json\/wp\/v2\/intolerancia?post=14843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}