{"id":48558,"date":"2020-02-11T11:07:49","date_gmt":"2020-02-11T11:07:49","guid":{"rendered":"https:\/\/www.galloportugal.com\/?post_type=momento&#038;p=48558"},"modified":"2020-05-12T15:18:16","modified_gmt":"2020-05-12T15:18:16","slug":"verbringen-sie-am-valentinstag-schoenen-momente-zu-zweit","status":"publish","type":"momento","link":"https:\/\/galloportugal.com\/de\/verbringen-sie-am-valentinstag-schoenen-momente-zu-zweit\/","title":{"rendered":"Verbringen Sie am Valentinstag sch\u00f6nen Momente zu zweit"},"content":{"rendered":"<p>Ein Men\u00fc, zubereitet von vier H\u00e4nden bedeutet Spa\u00df, Freude und die ist bekannterma\u00dfen am besten geteilt. Der perfekte Zeitpunkt, um loszulassen, sich zu unterhalten und sich n\u00e4her zu kommen, ganz ohne Eile und Ablenkung. Folgen Sie unseren Vorschl\u00e4gen, um die Gesellschaft zu genie\u00dfen, die sie am liebsten haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine besondere Nacht erfordert ein besonderes Programm. Die perfekte Gelegenheit, um<br \/>\nneue Erinnerungen und Momente von trauter Zweisamkeit zu erschaffen?<\/p>\n","protected":false},"featured_media":56199,"parent":0,"template":"","meta":[],"class_list":["post-48558","momento","type-momento","status-publish","has-post-thumbnail","hentry","momentos_category-zu-zweit"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/galloportugal.com\/de\/wp-json\/wp\/v2\/momento\/48558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galloportugal.com\/de\/wp-json\/wp\/v2\/momento"}],"about":[{"href":"https:\/\/galloportugal.com\/de\/wp-json\/wp\/v2\/types\/momento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galloportugal.com\/de\/wp-json\/wp\/v2\/media\/56199"}],"wp:attachment":[{"href":"https:\/\/galloportugal.com\/de\/wp-json\/wp\/v2\/media?parent=48558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}